{"id":2972,"count":0,"description":"","link":"http:\/\/www.cvprimasolo.com\/blog\/tag\/medical-device-accessories-4045-b2465e\/","name":"Medical Device Accessories","slug":"medical-device-accessories-4045-b2465e","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.cvprimasolo.com\/blog\/wp-json\/wp\/v2\/tags\/2972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.cvprimasolo.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.cvprimasolo.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.cvprimasolo.com\/blog\/wp-json\/wp\/v2\/posts?tags=2972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}