{"id":2996,"count":0,"description":"","link":"http:\/\/www.cvprimasolo.com\/blog\/tag\/carbon-fiber-fork-43d8-e5f012\/","name":"Carbon Fiber Fork","slug":"carbon-fiber-fork-43d8-e5f012","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"http:\/\/www.cvprimasolo.com\/blog\/wp-json\/wp\/v2\/tags\/2996","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.cvprimasolo.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.cvprimasolo.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.cvprimasolo.com\/blog\/wp-json\/wp\/v2\/posts?tags=2996"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}